{"id":9574,"date":"2026-05-20T15:06:58","date_gmt":"2026-05-20T15:06:58","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/quasars-of-destiny\/"},"modified":"2026-05-20T15:06:58","modified_gmt":"2026-05-20T15:06:58","slug":"quasars-of-destiny","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/quasars-of-destiny\/","title":{"rendered":"Quasars Of Destiny"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[31],"country":[42],"class_list":["post-9574","artist","type-artist","status-publish","hentry","genre-progressive-electronic","country-multi-national"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/9574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=9574"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=9574"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=9574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}