{"id":9058,"date":"2026-05-20T15:06:29","date_gmt":"2026-05-20T15:06:29","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/perspective-x-iv\/"},"modified":"2026-05-20T15:06:29","modified_gmt":"2026-05-20T15:06:29","slug":"perspective-x-iv","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/perspective-x-iv\/","title":{"rendered":"Perspective X Iv"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[50],"country":[16],"class_list":["post-9058","artist","type-artist","status-publish","hentry","genre-progressive-metal","country-united-states"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/9058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=9058"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=9058"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=9058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}