{"id":8986,"date":"2026-05-20T15:06:25","date_gmt":"2026-05-20T15:06:25","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/pearls-before-swine\/"},"modified":"2026-05-20T15:06:25","modified_gmt":"2026-05-20T15:06:25","slug":"pearls-before-swine","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/pearls-before-swine\/","title":{"rendered":"Pearls Before Swine"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[23],"country":[16],"class_list":["post-8986","artist","type-artist","status-publish","hentry","genre-prog-folk","country-united-states"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/8986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=8986"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=8986"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=8986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}