{"id":8181,"date":"2026-05-20T15:05:43","date_gmt":"2026-05-20T15:05:43","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/new-eden-orchestra\/"},"modified":"2026-05-20T15:05:43","modified_gmt":"2026-05-20T15:05:43","slug":"new-eden-orchestra","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/new-eden-orchestra\/","title":{"rendered":"New Eden Orchestra"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[41],"country":[16],"class_list":["post-8181","artist","type-artist","status-publish","hentry","genre-neo-prog","country-united-states"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/8181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=8181"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=8181"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=8181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}