{"id":7811,"date":"2026-05-20T15:05:25","date_gmt":"2026-05-20T15:05:25","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/morse-neal\/"},"modified":"2026-05-20T15:05:25","modified_gmt":"2026-05-20T15:05:25","slug":"morse-neal","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/morse-neal\/","title":{"rendered":"Morse, Neal"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[15],"country":[16],"class_list":["post-7811","artist","type-artist","status-publish","hentry","genre-symphonic-prog","country-united-states"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/7811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=7811"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=7811"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=7811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}