{"id":681,"date":"2026-05-20T15:02:10","date_gmt":"2026-05-20T15:02:10","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/amesoeurs\/"},"modified":"2026-05-20T15:02:10","modified_gmt":"2026-05-20T15:02:10","slug":"amesoeurs","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/amesoeurs\/","title":{"rendered":"Amesoeurs"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[19],"country":[30],"class_list":["post-681","artist","type-artist","status-publish","hentry","genre-experimental-post-metal","country-france"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=681"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=681"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}