{"id":6764,"date":"2026-05-20T15:04:35","date_gmt":"2026-05-20T15:04:35","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/liquid-tension-experiment\/"},"modified":"2026-05-20T15:04:35","modified_gmt":"2026-05-20T15:04:35","slug":"liquid-tension-experiment","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/liquid-tension-experiment\/","title":{"rendered":"Liquid Tension Experiment"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[50],"country":[16],"class_list":["post-6764","artist","type-artist","status-publish","hentry","genre-progressive-metal","country-united-states"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/6764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=6764"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=6764"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=6764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}