{"id":6220,"date":"2026-05-20T15:04:12","date_gmt":"2026-05-20T15:04:12","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/kevel\/"},"modified":"2026-05-20T15:04:12","modified_gmt":"2026-05-20T15:04:12","slug":"kevel","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/kevel\/","title":{"rendered":"Kevel"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[19],"country":[47],"class_list":["post-6220","artist","type-artist","status-publish","hentry","genre-experimental-post-metal","country-greece"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/6220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=6220"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=6220"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=6220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}