{"id":5595,"date":"2026-05-20T15:03:52","date_gmt":"2026-05-20T15:03:52","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/ielasi-giuseppe\/"},"modified":"2026-05-20T15:03:52","modified_gmt":"2026-05-20T15:03:52","slug":"ielasi-giuseppe","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/ielasi-giuseppe\/","title":{"rendered":"Ielasi, Giuseppe"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[31],"country":[18],"class_list":["post-5595","artist","type-artist","status-publish","hentry","genre-progressive-electronic","country-italy"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/5595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=5595"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=5595"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=5595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}