{"id":5594,"date":"2026-05-20T15:03:52","date_gmt":"2026-05-20T15:03:52","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/idle-heirs\/"},"modified":"2026-05-20T15:03:52","modified_gmt":"2026-05-20T15:03:52","slug":"idle-heirs","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/idle-heirs\/","title":{"rendered":"Idle Heirs"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[19],"country":[16],"class_list":["post-5594","artist","type-artist","status-publish","hentry","genre-experimental-post-metal","country-united-states"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/5594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=5594"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=5594"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=5594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}