{"id":4677,"date":"2026-05-20T15:03:24","date_gmt":"2026-05-20T15:03:24","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/general-purpose\/"},"modified":"2026-05-20T15:03:24","modified_gmt":"2026-05-20T15:03:24","slug":"general-purpose","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/general-purpose\/","title":{"rendered":"General Purpose"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[36],"country":[16],"class_list":["post-4677","artist","type-artist","status-publish","hentry","genre-crossover-prog","country-united-states"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/4677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=4677"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=4677"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=4677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}