{"id":3763,"date":"2026-05-20T15:03:03","date_gmt":"2026-05-20T15:03:03","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/endoplasmic-flow\/"},"modified":"2026-05-20T15:03:03","modified_gmt":"2026-05-20T15:03:03","slug":"endoplasmic-flow","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/endoplasmic-flow\/","title":{"rendered":"Endoplasmic Flow"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[31],"country":[42],"class_list":["post-3763","artist","type-artist","status-publish","hentry","genre-progressive-electronic","country-multi-national"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/3763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=3763"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=3763"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=3763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}