{"id":3735,"date":"2026-05-20T15:03:02","date_gmt":"2026-05-20T15:03:02","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/empire-bathtub\/"},"modified":"2026-05-20T15:03:02","modified_gmt":"2026-05-20T15:03:02","slug":"empire-bathtub","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/empire-bathtub\/","title":{"rendered":"Empire Bathtub"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[17],"country":[16],"class_list":["post-3735","artist","type-artist","status-publish","hentry","genre-heavy-prog","country-united-states"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/3735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=3735"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=3735"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=3735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}