{"id":3104,"date":"2026-05-20T15:02:50","date_gmt":"2026-05-20T15:02:50","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/deigen\/"},"modified":"2026-05-20T15:02:50","modified_gmt":"2026-05-20T15:02:50","slug":"deigen","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/deigen\/","title":{"rendered":"Deigen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[26],"country":[46],"class_list":["post-3104","artist","type-artist","status-publish","hentry","genre-psychedelic-space-rock","country-japan"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/3104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=3104"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=3104"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=3104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}