{"id":3076,"date":"2026-05-20T15:02:49","date_gmt":"2026-05-20T15:02:49","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/decadence\/"},"modified":"2026-05-20T15:02:49","modified_gmt":"2026-05-20T15:02:49","slug":"decadence","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/decadence\/","title":{"rendered":"Decadence"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[50],"country":[48],"class_list":["post-3076","artist","type-artist","status-publish","hentry","genre-progressive-metal","country-russia"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/3076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=3076"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=3076"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=3076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}