{"id":1550,"date":"2026-05-20T15:02:23","date_gmt":"2026-05-20T15:02:23","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/bear-bones-lay-low\/"},"modified":"2026-05-20T15:02:23","modified_gmt":"2026-05-20T15:02:23","slug":"bear-bones-lay-low","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/bear-bones-lay-low\/","title":{"rendered":"Bear Bones Lay Low"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[31],"country":[85],"class_list":["post-1550","artist","type-artist","status-publish","hentry","genre-progressive-electronic","country-venezuela"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/1550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=1550"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=1550"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=1550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}