{"id":13117,"date":"2026-05-20T15:10:51","date_gmt":"2026-05-20T15:10:51","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/zen-carnival\/"},"modified":"2026-05-20T15:10:51","modified_gmt":"2026-05-20T15:10:51","slug":"zen-carnival","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/zen-carnival\/","title":{"rendered":"Zen Carnival"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[36],"country":[16],"class_list":["post-13117","artist","type-artist","status-publish","hentry","genre-crossover-prog","country-united-states"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/13117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=13117"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=13117"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=13117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}