{"id":12108,"date":"2026-05-20T15:09:37","date_gmt":"2026-05-20T15:09:37","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/turbulence\/"},"modified":"2026-05-20T15:09:37","modified_gmt":"2026-05-20T15:09:37","slug":"turbulence","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/turbulence\/","title":{"rendered":"Turbulence"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[50],"country":[61],"class_list":["post-12108","artist","type-artist","status-publish","hentry","genre-progressive-metal","country-lebanon"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/12108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=12108"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=12108"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=12108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}