{"id":12091,"date":"2026-05-20T15:09:36","date_gmt":"2026-05-20T15:09:36","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/tulipe-noire-la\/"},"modified":"2026-05-20T15:09:36","modified_gmt":"2026-05-20T15:09:36","slug":"tulipe-noire-la","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/tulipe-noire-la\/","title":{"rendered":"Tulipe Noire, La"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[41],"country":[47],"class_list":["post-12091","artist","type-artist","status-publish","hentry","genre-neo-prog","country-greece"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/12091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=12091"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=12091"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=12091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}