{"id":11985,"date":"2026-05-20T15:09:29","date_gmt":"2026-05-20T15:09:29","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/trephine\/"},"modified":"2026-05-20T15:09:29","modified_gmt":"2026-05-20T15:09:29","slug":"trephine","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/trephine\/","title":{"rendered":"Trephine"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[19],"country":[16],"class_list":["post-11985","artist","type-artist","status-publish","hentry","genre-experimental-post-metal","country-united-states"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/11985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=11985"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=11985"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=11985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}