{"id":11613,"date":"2026-05-20T15:09:03","date_gmt":"2026-05-20T15:09:03","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/terminal-degree\/"},"modified":"2026-05-20T15:09:03","modified_gmt":"2026-05-20T15:09:03","slug":"terminal-degree","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/terminal-degree\/","title":{"rendered":"Terminal Degree"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[17],"country":[16],"class_list":["post-11613","artist","type-artist","status-publish","hentry","genre-heavy-prog","country-united-states"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/11613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=11613"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=11613"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=11613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}