{"id":11096,"date":"2026-05-20T15:08:30","date_gmt":"2026-05-20T15:08:30","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/stazione-delle-frequenze-la\/"},"modified":"2026-05-20T15:08:30","modified_gmt":"2026-05-20T15:08:30","slug":"stazione-delle-frequenze-la","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/stazione-delle-frequenze-la\/","title":{"rendered":"Stazione Delle Frequenze, La"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[58],"country":[18],"class_list":["post-11096","artist","type-artist","status-publish","hentry","genre-rock-progressivo-italiano","country-italy"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/11096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=11096"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=11096"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=11096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}