{"id":10564,"date":"2026-05-20T15:07:57","date_gmt":"2026-05-20T15:07:57","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/silent-grace\/"},"modified":"2026-05-20T15:07:57","modified_gmt":"2026-05-20T15:07:57","slug":"silent-grace","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/silent-grace\/","title":{"rendered":"Silent Grace"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[34],"country":[51],"class_list":["post-10564","artist","type-artist","status-publish","hentry","genre-eclectic-prog","country-ukraine"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/10564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=10564"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=10564"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=10564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}