{"id":10406,"date":"2026-05-20T15:07:48","date_gmt":"2026-05-20T15:07:48","guid":{"rendered":"https:\/\/musicapp2.salite.top\/index.php\/artist\/seven\/"},"modified":"2026-05-20T15:07:48","modified_gmt":"2026-05-20T15:07:48","slug":"seven","status":"publish","type":"artist","link":"https:\/\/musicapp2.salite.top\/index.php\/artist\/seven\/","title":{"rendered":"Seven"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","genre":[19],"country":[16],"class_list":["post-10406","artist","type-artist","status-publish","hentry","genre-experimental-post-metal","country-united-states"],"acpt":null,"_links":{"self":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist\/10406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/types\/artist"}],"wp:attachment":[{"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/media?parent=10406"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/genre?post=10406"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/musicapp2.salite.top\/index.php\/wp-json\/wp\/v2\/country?post=10406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}